{"id":8442,"date":"2024-07-03T19:30:39","date_gmt":"2024-07-03T22:30:39","guid":{"rendered":"https:\/\/www.jotapostaok.com.ar\/?p=8442"},"modified":"2026-04-25T12:23:15","modified_gmt":"2026-04-25T12:23:15","slug":"jjoo-paris-2024-todo-lo-que-tenes-que-saber","status":"publish","type":"post","link":"https:\/\/jotaposta.com.ar\/jposta\/2024\/07\/03\/jjoo-paris-2024-todo-lo-que-tenes-que-saber\/","title":{"rendered":"JJOO Par\u00eds 2024: Todo lo que tenes que saber"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los Juegos Ol\u00edmpicos son la gran cita deportiva de la temporada. Por tercera vez en su historia la capital francesa recibir\u00e1 esta fiesta multidisciplinaria (las anteriores fueron en 1900 y en 1924). \u00a0que concentra la atenci\u00f3n de buena parte del mundo por poco m\u00e1s de dos semanas y que cautiva la atenci\u00f3n de los fan\u00e1ticos del deporte pero tambi\u00e9n de aquellos que no lo son y se ven encandilados por el fen\u00f3meno que provocan. En #JotaPosta nos ponemos a tono y te contamos todo lo que tenes que saber.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cadenaser.com\/resizer\/v2\/NM3DNWDXZRGWXFGEK6GQOMEL6I.jpg?auth=9c6e79ba60932239280e4643622662ca20a5ade8f423de3203146a791693590f&amp;quality=70&amp;width=650&amp;height=487&amp;smart=true\" alt=\"C\u00f3mo se llama la mascota de los Juegos Ol\u00edmpicos de Par\u00eds 2024? | Deportes  | Cadena SER\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Par\u00eds 2024 se desarrollar\u00e1 entre el 26 de julio y 11 de\nagosto pr\u00f3ximos. Ser\u00e1n 19 d\u00edas de competencia en 32 deportes, con 329 eventos\nen 762 sesiones. La Argentina, en tanto, ya tiene asegurada la participaci\u00f3n de\n&nbsp;135 atletas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de las disciplinas se llevar\u00e1n a cabo en Par\u00eds y en su \u00e1rea metropolitana, pero otras tantas se realizar\u00e1n a varios kil\u00f3metros del epicentro. Versalles ser\u00e1 sede de deportes ecuestres, pentatl\u00f3n moderno, ciclismo y golf. En Lille se jugar\u00e1n los torneos de handball y b\u00e1squetbol. Chateauroux, en tanto, albergar\u00e1 los eventos de tiro, y Marsella los de vela. El f\u00fatbol, como es habitual, se repartir\u00e1 en siete estadios: Parc des Princes (Par\u00eds), Estadio de la Beaujoire (Nantes), Parc Olympique Lyonnais (Lyon), Estadio Geoffroy-Guichard (Saint-\u00c9tienne), Estadio Matmut Atlantique (Burdeos), Allianz Riviera (Niza) y Stade V\u00e9lodrome (Marsella).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.infobae.com\/new-resizer\/z0uCD3aGGk7FcwqpUAX7_Vdfe5U=\/1440x810\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/6LCWWGG5Q5BKNDQH6SG44S2BYQ.jpg\" alt=\"Todos los deportistas argentinos clasificados para los Juegos Ol\u00edmpicos  tras el triunfo del f\u00fatbol masculino: el n\u00famero de plazas y el camino a  Par\u00eds - Infobae\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Informaci\u00f3n sobre las medallas: habr\u00e1 un total de 5.084 medallas producidas. Cada una de ellas tiene un di\u00e1metro de 85 mil\u00edmetros, un grosor de 9.2 mil\u00edmetros. Las de oro pesar\u00e1n 529 gramos, las de plata 525 y las de bronce 455.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/statics.diariomendoza.com.ar\/2023\/11\/crop\/65478517e9158__400x300.webp\" alt=\"Uno por uno, los clasificados de la Delegaci\u00f3n Argentina a los Juegos  Ol\u00edmpicos Par\u00eds 2024 - Diario Mendoza\" width=\"535\" height=\"401\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La delegaci\u00f3n Argentina Completa:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Atletismo<\/strong>&nbsp;(6):\n     Florencia Borelli, Daiana Ocampo (marat\u00f3n), Eli\u00e1n Larregina (400 metros),\n     Bel\u00e9n Casetta (3 mil metros con obst\u00e1culos), Nazareno Sasia (lanzamiento\n     de bala) y Joaqu\u00edn G\u00f3mez (lanzamiento de martillo).<\/li><li><strong>BMX<\/strong>&nbsp;(2):\n     Gonzalo Molina y Jos\u00e9 Augusto Torres.<\/li><li><strong>Canotaje&nbsp;<\/strong>(2):\n     Agust\u00edn Vernice (K1 1000m) y Brenda Rojas (K1 500).<\/li><li><strong>Ciclismo de ruta&nbsp;<\/strong>(1):\n     Eduardo Sep\u00falveda.<\/li><li><strong>Equitaci\u00f3n&nbsp;<\/strong>(3):\n     Jos\u00e9 Mar\u00eda Larocca (salto) y dos plazas en Concurso Completo (a designar).<\/li><li><strong>Esgrima&nbsp;<\/strong>(1):\n     Pascual Di Tella (sable)<\/li><li><strong>F\u00fatbol&nbsp;<\/strong>(18):\n     la Selecci\u00f3n Argentina Sub-23 masculina, con hasta 3 jugadores mayores.<\/li><li><strong>Golf&nbsp;<\/strong>(2):\n     Alejandro Tosti y Emiliano Grillo.<\/li><li><strong>Handball&nbsp;<\/strong>(14):\n     Leonel Maciel, Juan Bar, Diego Simonet, Pablo Simonet, Pedro Mart\u00ednez\n     Cami, Nicol\u00e1s Bono, Ignacio Pizarro, Federico Fern\u00e1ndez, Santiago Baronetto,\n     Lucas Moscariello, Gast\u00f3n Mouri\u00f1o, Pablo Vainstein, Federico Pizarro,\n     Nicol\u00e1s Bonanno, James Parker, Andr\u00e9s Moyano y Guillermo Fischer.<\/li><li><strong>Hockey sobre c\u00e9sped<\/strong>&nbsp;(32):\n     Las Leonas &#8211; Cristina Cosentino, Juana Castellaro Morello, Valentina\n     Raposo, Agustina Gorzelany, Victoria Sauze, Agostina Alonso, Roc\u00edo S\u00e1nchez\n     Moccia, Pilar Campoy, Sof\u00eda Cair\u00f3, Sof\u00eda Toccalino, Eugenia Trinchinetti,\n     Mar\u00eda Jos\u00e9 Granatto, Agustina Albertario, Lara Casas, Zoe D\u00edaz y Julieta\n     Jankunas. Los Leones &#8211; Tomas Santiago, Juan Ignacio Catan, Nicol\u00e1s Della\n     Torre, Tadeo Marcucci, I\u00f1aki Minadeo, Federico Monja, Agustin Bugallo,\n     Thomas Habif, Matias Rey, Santiago Tarazona, Lucas Toscani, Bautista\n     Capurro, Maico Casella, Tom\u00e1s Domene, Lucas Martinez y Agustin Mazzilli.<\/li><li><strong>Nataci\u00f3n&nbsp;<\/strong>(2):\n     Macarena Ceballos (100m pecho) y Ulises Saravia (100m espalda).<\/li><li><strong>Pentatl\u00f3n Moderno&nbsp;<\/strong>(1):\n     Franco Serrano.<\/li><li><strong>Remo&nbsp;<\/strong>(4):\n     Sonia Baluzzo y Evelyn Silvestro (LW2x) y Alejandro Colomino y Pedro\n     Dickson (LM2x).<\/li><li><strong>Rugby&nbsp;<\/strong>(12):\n     plantel de Los Pumas 7s, a confirmar.<\/li><li><strong>Skateboarding&nbsp;<\/strong>(2):\n     Mat\u00edas Dell Olio y Mauro Iglesias.<\/li><li><strong>Taekwondo&nbsp;<\/strong>(1):\n     Lucas Guzm\u00e1n (-58 kg).<\/li><li><strong>Tenis&nbsp;<\/strong>(8):\n     Sebasti\u00e1n B\u00e1ez, Francisco Cer\u00fandolo, Tom\u00e1s Etcheverry, Mariano Navone,\n     Lourdes Carl\u00e9, Nadia Podoroska, M\u00e1ximo \u2018Machi\u2019 Gonz\u00e1lez y Andr\u00e9s Molteni.<\/li><li><strong>Tenis de mesa<\/strong>&nbsp;(1):\n     Santiago Lorenzo.<\/li><li><strong>Tiro&nbsp;<\/strong>(3):\n     Fernanda Russo (rifle de aire a 10m), Juli\u00e1n Guti\u00e9rrez ((rifle de aire a\n     10m) y Federico Gil (skeet).<\/li><li><strong>Tiro con arco<\/strong>&nbsp;(1):\n     Dami\u00e1n Jajarabilla (recurvo individual).<\/li><li><strong>Triatl\u00f3n&nbsp;<\/strong>(1):\n     Romina Biagioli.<\/li><li><strong>Vela&nbsp;<\/strong>(7):\n     Eugenia Bosco y Mateo Majdalani (Nacra 17), Luc\u00eda Falasca (ILCA 6),\n     Catalina Turienzo (F\u00f3rmula Kite), Francisco Saubidet y Chiara Ferreti\n     (ambos en windsurf) y Francisco Guaragna (ILCA 7).<\/li><li><strong>V\u00f3leibol masculino (12):<\/strong>&nbsp;Plantel\n     a definir.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Los Juegos Ol\u00edmpicos son la gran cita deportiva de la temporada. Por tercera vez en su historia la capital francesa recibir\u00e1 esta fiesta multidisciplinaria (las anteriores fueron en 1900 y en 1924). \u00a0que concentra la atenci\u00f3n de buena parte del mundo por poco m\u00e1s de dos semanas y que cautiva la atenci\u00f3n de los fan\u00e1ticos &hellip;<\/p>\n","protected":false},"author":1,"featured_media":8443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","iawp_total_views":10,"footnotes":""},"categories":[4,25],"tags":[],"class_list":["post-8442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-politica","category-resumen-de-noticias"],"_links":{"self":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts\/8442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/comments?post=8442"}],"version-history":[{"count":1,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts\/8442\/revisions"}],"predecessor-version":[{"id":13275,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts\/8442\/revisions\/13275"}],"wp:attachment":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/media?parent=8442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/categories?post=8442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/tags?post=8442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}