{"id":5398,"date":"2020-01-27T03:00:57","date_gmt":"2020-01-27T06:00:57","guid":{"rendered":"https:\/\/www.jotaposta.com.ar\/?p=5398"},"modified":"2020-01-27T03:00:57","modified_gmt":"2020-01-27T06:00:57","slug":"por-que-el-27-de-enero-se-conmemora-a-las-victimas-del-holocausto","status":"publish","type":"post","link":"https:\/\/jotaposta.com.ar\/jposta\/2020\/01\/27\/por-que-el-27-de-enero-se-conmemora-a-las-victimas-del-holocausto\/","title":{"rendered":"\u00bfPor qu\u00e9 el 27 de Enero se Conmemora a las V\u00edctimas del Holocausto?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Estos \u00faltimos d\u00edas fue noticia la decisi\u00f3n de Alberto Fern\u00e1ndez de elegir su primer destino internacional como presidente a Israel, para as\u00ed poder asistir al evento que conmemora el 75\u00b0aniversario de la ca\u00edda de Auschwitz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En <strong>#JotaPosta te contaremos porque se trata de una fecha tan importante para el pueblo jud\u00edo.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Un poco de Historia.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 1 de Noviembre de 2005 la Organizaci\u00f3n de las Naciones Unidas (ONU) design\u00f3 al 27 de enero como D\u00eda Internacional de Conmemoraci\u00f3n en Memoria de las V\u00edctimas del Holocausto.<\/p>\n\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5399\" src=\"https:\/\/www.jotaposta.com.ar\/wp-content\/uploads\/2020\/01\/holocausto1.jpg\" alt=\"\" width=\"574\" height=\"321\" \/><\/figure>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Aquel d\u00eda, pero de 1945, fuerzas sovi\u00e9ticas conocidas como el Ej\u00e9rcito Rojo rescataron a miles de prisioneros jud\u00edos del campo de concentraci\u00f3n de Auschwitz, el mayor centro de exterminio en la historia nazi, ubicado en Polonia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Custodiada por la SS, organizaci\u00f3n militar y policial al servicio de Adolf Hitler, se estima que entre 1940 y 1945 &#8220;alberg\u00f3&#8221; como prisioneros a m\u00e1s de\u00a0 2 millones de personas.<\/p>\n\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5400\" src=\"https:\/\/www.jotaposta.com.ar\/wp-content\/uploads\/2020\/01\/holocausto2.jpg\" alt=\"\" width=\"597\" height=\"419\" \/><\/figure>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">All\u00ed se vivi\u00f3 a la m\u00e1xima expresi\u00f3n el terror del nazismo. Desde que el F\u00fchrer tom\u00f3 el poder en Alemania, all\u00e1 por 1933, la persecuci\u00f3n a las minor\u00edas \u00e9tnicas fue siempre una constante, pero ya a fines de la d\u00e9cada del 30 hizo un giro radical que consisti\u00f3 en matanzas, experimentaciones y torturas sistem\u00e1ticas. Fue en 1940 cuando se llev\u00f3 a cabo la repudiable Soluci\u00f3n Final, proyecto que consisti\u00f3 en la construcci\u00f3n de campos de concentraci\u00f3n a lo largo y ancho de los territorios nazis donde iban a parar los &#8220;Enemigos de Alemania&#8221; para su posterior aniquilaci\u00f3n. Ese a\u00f1o fue creado el centro de terror de Auschwitz , cuyas c\u00e1maras de gas y hornos fueron los que m\u00e1s vidas se llevaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los campos de concentraci\u00f3n, y principalmente en \u00e9ste, no solo llegaban jud\u00edos, sino tambi\u00e9n prisioneros de guerra que eran obligados a hacer trabajos forzosos. De hecho, en la entrada del establecimiento, hab\u00eda un letrero que dec\u00eda &#8220;Arbeit macht frei&#8221;, que en alem\u00e1n significa, &#8220;el trabajo hace libre&#8221;.<\/p>\n\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5401\" src=\"https:\/\/www.jotaposta.com.ar\/wp-content\/uploads\/2020\/01\/holocausto3.jpg\" alt=\"\" width=\"612\" height=\"463\" \/><\/figure>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Situado al 43 km al oeste de Cracovia, se estima que murieron 1.100.000 de personas, de las cuales un 90% eran jud\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para enero de 1945 la guerra se empezaba a inclinar claramente del lado de las fuerzas Aliadas y, ante el avance incontenible del Ej\u00e9rcito Rojo en suelo Polaco, el 17 de enero los alemanes en Auschwitz\u00a0 decidieron huir, llev\u00e1ndose consigo a miles de\u00a0 prisioneros, de los cuales muchos terminaron muriendo en esa traves\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"746\" class=\"wp-image-5404\" src=\"https:\/\/www.jotaposta.com.ar\/wp-content\/uploads\/2020\/01\/holoc2-1024x746.jpg\" alt=\"\" srcset=\"https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc2-1024x746.jpg 1024w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc2-300x219.jpg 300w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc2-768x560.jpg 768w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc2.jpg 1072w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando llegaron los rusos, 10 d\u00edas m\u00e1s tarde, se encontraron con un campo en ruinas y numerosas cantidad de fosas que apilaban miles y miles de cad\u00e1veres y adem\u00e1s cientos de prisioneros que hab\u00edan logrado sobrevivir.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" class=\"wp-image-5403\" src=\"https:\/\/www.jotaposta.com.ar\/wp-content\/uploads\/2020\/01\/holca1-1024x576.jpg\" alt=\"\" srcset=\"https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holca1-1024x576.jpg 1024w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holca1-300x169.jpg 300w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holca1-768x432.jpg 768w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holca1-390x220.jpg 390w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holca1.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Anatoly Shapiro, el primer soldado aliado en pisar Auschwitz , revelar\u00eda a\u00f1os m\u00e1s tarde que sinti\u00f3 una profunda sorpresa y espanto cuando vio el lugar con el que se encontr\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho marc\u00f3 en definitiva el fin del holocausto. El mayor centro de exterminio alem\u00e1n, no funcionaba m\u00e1s.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"594\" class=\"wp-image-5407\" src=\"https:\/\/www.jotaposta.com.ar\/wp-content\/uploads\/2020\/01\/Museo-Judio-Israel-1024x594.jpg\" alt=\"\" srcset=\"https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/Museo-Judio-Israel-1024x594.jpg 1024w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/Museo-Judio-Israel-300x174.jpg 300w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/Museo-Judio-Israel-768x446.jpg 768w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/Museo-Judio-Israel-1536x891.jpg 1536w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/Museo-Judio-Israel.jpg 1960w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n<figcaption>Visitantes en el Museo del Holocausto de Jerusal\u00e9n. (AFP)<\/figcaption>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Lo cierto es que el debilitamiento alem\u00e1n se acentu\u00f3 en los meses posteriores y finalmente, el 8 de mayo, el pa\u00eds firmar\u00eda la capitulaci\u00f3n en Berl\u00edn, dando as\u00ed el fin de la segunda Guerra Mundial en Europa.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" class=\"wp-image-5405\" src=\"https:\/\/www.jotaposta.com.ar\/wp-content\/uploads\/2020\/01\/holoc3-1024x576.jpg\" alt=\"\" srcset=\"https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc3-1024x576.jpg 1024w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc3-300x169.jpg 300w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc3-768x432.jpg 768w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc3-1536x864.jpg 1536w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc3-390x220.jpg 390w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/holoc3.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Memoria<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o se cumplen 75 a\u00f1os, por tanto Israel se prepara para festejos y tamb\u00eden para el Quinto Foro Mundial del Holocausto, que se llevara a cabo Jerusal\u00e9n y contar\u00e1 con la presencia, entre otros l\u00edderes mundiales, de Alberto Fern\u00e1ndez. Adem\u00e1s los eventos incluir\u00e1n una conferencia acad\u00e9mica y una ceremonia de conmemoraci\u00f3n en la Sede de la UNESCO, as\u00ed como exposiciones en Par\u00eds y en otras varias oficinas de la UNESCO.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"822\" height=\"547\" class=\"wp-image-5406\" src=\"https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/Alberto-Fernandez-Israel.jpg\" alt=\"\" srcset=\"https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/Alberto-Fernandez-Israel.jpg 822w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/Alberto-Fernandez-Israel-300x200.jpg 300w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2020\/01\/Alberto-Fernandez-Israel-768x511.jpg 768w\" sizes=\"auto, (max-width: 822px) 100vw, 822px\" \/>\n<figcaption>Llegada de Alberto Fernandez a Isarael<\/figcaption>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estos \u00faltimos d\u00edas fue noticia la decisi\u00f3n de Alberto Fern\u00e1ndez de elegir su primer destino internacional como presidente a Israel, para as\u00ed poder asistir al evento que conmemora el 75\u00b0aniversario de la ca\u00edda de Auschwitz. En #JotaPosta te contaremos porque se trata de una fecha tan importante para el pueblo jud\u00edo. Un poco de Historia. &hellip;<\/p>\n","protected":false},"author":1,"featured_media":5408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","iawp_total_views":6,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts\/5398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/comments?post=5398"}],"version-history":[{"count":0,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts\/5398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/media\/5408"}],"wp:attachment":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/media?parent=5398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/categories?post=5398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/tags?post=5398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}