{"id":2515,"date":"2018-10-29T09:20:41","date_gmt":"2018-10-29T12:20:41","guid":{"rendered":"https:\/\/www.jotaposta.com.ar\/?p=2515"},"modified":"2018-10-29T09:20:41","modified_gmt":"2018-10-29T12:20:41","slug":"2515","status":"publish","type":"post","link":"https:\/\/jotaposta.com.ar\/jposta\/2018\/10\/29\/2515\/","title":{"rendered":"La Alimentaci\u00f3n de los Ni\u00f1@s es Fundamental para su Desarrollo F\u00edsico y Mental"},"content":{"rendered":"<p>La alimentaci\u00f3n es fundamental para un mejor desarrollo en varios aspectos de nuestras vidas, pero sobre todo cuando se trata de los ni\u00f1@s.<\/p>\n<p>Actualmente el ritmo de vida de muchos, las diferentes actividades,el levantarse\u00a0 m\u00e1s temprano y dem\u00e1s hacen que los padres deban ofrecer a los ni\u00f1os una alimentaci\u00f3n capaz de brindarles los nutrientes adecuados para optimizar su desarrollo f\u00edsico y mental.<\/p>\n<p>Controlar el estado nutricional de los chicos se vuelve fundamental si lo que se desea es evitar alteraciones en su crecimiento. Por eso en <strong>#JotaPosta<\/strong> nos comunicamos con la <strong>Fundaci\u00f3n Cardiol\u00f3gica Argentina<\/strong>, quien a trav\u00e9s del asesoramiento de la<strong> Lic. en Nutrici\u00f3n Luciana Soledad Valeiras (MN 7192)<\/strong> nos brindaron algunos consejos para que los m\u00e1s chicos incorporen conductas que se transformen en h\u00e1bitos saludables que puedan sostener a los largo de la vida. Adoptarlas desde el comienzo de la escolaridad es fundamental para evitar enfermedades por exceso y\/o d\u00e9ficit.<\/p>\n<p><em>\u201cPara que los ni\u00f1os en edad escolar puedan desarrollarse correctamente, estar saludables y activos, deben realizar las 4 comidas principales y alguna colaci\u00f3n o refrigerio\u201d<\/em> comienza explicando la doctora.<\/p>\n<p><strong>El desayuno<\/strong><\/p>\n<p><em>\u201cEs la comida m\u00e1s importante del d\u00eda\u201d<\/em> recalca y agrega que <em>\u201cMuchas veces es pasado por alto por preferir dormir un rato m\u00e1s o no tener ganas de consumir alimentos. Sin embargo, es necesario que toda la familia tome el h\u00e1bito de desayunar, en lo posible tratar de sentarse a la mesa con los ni\u00f1os y explicarles que no es una comida m\u00e1s. Es la comida donde se incorpora energ\u00eda en el momento que m\u00e1s lo necesitan\u201d.<\/em><\/p>\n<p><em>\u201cUn desayuno completo debe incluir alimentos que contengan calcio y prote\u00ednas (nutrientes necesarios para el desarrollo y crecimiento), hidratos de carbono complejos, fibra, vitaminas y minerales<\/em>\u201d informa Valeiras.<\/p>\n<p><strong>Media Ma\u00f1ana<\/strong><\/p>\n<p>En este aspecto la nutricionista refiere que <em>\u201ctradicionalmente, en los kioscos de las escuelas predominaba la oferta de alimentos procesados o industrializados con alto contenido de az\u00facares refinados y grasas, como snacks, gaseosas azucaradas, golosinas, entre otros, que solo aportan \u201ccalor\u00edas vac\u00edas\u201d\u201d.<\/em><\/p>\n<p>No obstante aclara que<em> \u201cAfortunadamente, e impulsados por la Ley N\u00b0 3704 de Alimentaci\u00f3n Saludable de la Ciudad de Buenos Aires, hoy podemos asegurarnos en los kioscos de las escuelas alimentos ricos en vitaminas, minerales y prote\u00ednas que aportan a los ni\u00f1os nutrientes y energ\u00eda; incluidos dentro de las Gu\u00edas de Alimentos y Bebidas Saludables (GABS)\u201d.<\/em><\/p>\n<p><em>\u201cDe todas maneras, siempre es m\u00e1s saludable y econ\u00f3mico preparar los alimentos en casa en forma de viandas para media ma\u00f1ana o la tarde\u201d<\/em> detalla.<\/p>\n<p><strong>El almuerzo<\/strong><\/p>\n<p>En los casos en donde los ni\u00f1os tienen que almorzar en el colegio, y tiene que llevar sus alimentos, es importante tambi\u00e9n<em> \u201cpoder planificarlo con anticipaci\u00f3n ya que es la mejor manera de elegir los alimentos saludables\u201d<\/em> explica Valeiras.<\/p>\n<p>Por \u00faltimo, y no menos importante es la hidrataci\u00f3n durante todo el d\u00eda:<em> \u201cSiempre es conveniente que el ni\u00f1o tenga su propia botella cargada con agua y as\u00ed evitar que consuma gaseosas o jugos azucarados. En caso que no le guste el agua se puede optar por limonadas o jugos de naranja exprimido\u201d<\/em> anuncia la doctora.<\/p>\n<p>Para finalizar, siempre es importante tener en casa alimentos saludables, para que los ni\u00f1os a la hora de elegir tengan una<em> \u201calternativa segura y no se dejen tentar por opciones que solo da\u00f1an su salud\u201d<\/em> sentencia la profesional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La alimentaci\u00f3n es fundamental para un mejor desarrollo en varios aspectos de nuestras vidas, pero sobre todo cuando se trata de los ni\u00f1@s. Actualmente el ritmo de vida de muchos, las diferentes actividades,el levantarse\u00a0 m\u00e1s temprano y dem\u00e1s hacen que los padres deban ofrecer a los ni\u00f1os una alimentaci\u00f3n capaz de brindarles los nutrientes adecuados &hellip;<\/p>\n","protected":false},"author":1,"featured_media":2516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","iawp_total_views":9,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-2515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts\/2515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/comments?post=2515"}],"version-history":[{"count":0,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts\/2515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/media\/2516"}],"wp:attachment":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/media?parent=2515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/categories?post=2515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/tags?post=2515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}