{"id":2381,"date":"2018-10-08T12:12:06","date_gmt":"2018-10-08T15:12:06","guid":{"rendered":"https:\/\/www.jotaposta.com.ar\/?p=2381"},"modified":"2018-10-08T12:12:06","modified_gmt":"2018-10-08T15:12:06","slug":"la-plata-internos-confeccionan-carteles-en-braille-para-la-municipalidad","status":"publish","type":"post","link":"https:\/\/jotaposta.com.ar\/jposta\/2018\/10\/08\/la-plata-internos-confeccionan-carteles-en-braille-para-la-municipalidad\/","title":{"rendered":"La plata: Internos Confeccionan Carteles en Braille para la Municipalidad"},"content":{"rendered":"<p>En \u00e9pocas donde parece que el \u00fanico objetivo que presenta la c\u00e1rcel en la Argentina es el de \u201cperfeccionar\u201d a los delincuentes, aparecen noticias que conceden un haz de luz para quienes, como nosotros, aun creemos que ese sea un lugar para una futura reinserci\u00f3n.<\/p>\n<p>En esta oportunidad se trata de los internos de la Unidad nro. 9 de La Plata, que integran el <strong>Taller de Escritura\u00a0 en idioma braille.<\/strong><\/p>\n<figure id=\"attachment_2382\" aria-describedby=\"caption-attachment-2382\" style=\"width: 1033px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2382\" src=\"https:\/\/www.jotaposta.com.ar\/wp-content\/uploads\/2018\/10\/bnraille-2.jpg\" alt=\"\" width=\"1033\" height=\"645\" srcset=\"https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2018\/10\/bnraille-2.jpg 1033w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2018\/10\/bnraille-2-300x187.jpg 300w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2018\/10\/bnraille-2-1024x639.jpg 1024w, https:\/\/jotaposta.com.ar\/jposta\/wp-content\/uploads\/2018\/10\/bnraille-2-768x480.jpg 768w\" sizes=\"auto, (max-width: 1033px) 100vw, 1033px\" \/><figcaption id=\"caption-attachment-2382\" class=\"wp-caption-text\">Foto Gentileza El Dia<\/figcaption><\/figure>\n<p>Esta iniciativa, que cuenta con el apoyo de la Municipalidad local y el Ministerio de Justicia Bonaerense, implica la confecci\u00f3n de carteles en ese sistema que luego ser\u00e1n colocados a lo largo y ancho del edificio oficial. Esto permitir\u00e1 a personas ciegas ubicarse y orientarse de manera m\u00e1s sencilla.<\/p>\n<p><em>\u201cParticipar de estos espacios es tener momentos de libertad, poder alejarnos del pabell\u00f3n, sentir que estamos siendo \u00fatiles para la sociedad y tambi\u00e9n prepararnos para salir\u201d<\/em> detall\u00f3 uno de los internos que integra el taller.<\/p>\n<p>Vale recordar \u00a0que tiempo atr\u00e1s este grupo estuvo encargado de confeccionar se\u00f1aliticas para ser ubicadas en la Rep\u00fablica de los Ni\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En \u00e9pocas donde parece que el \u00fanico objetivo que presenta la c\u00e1rcel en la Argentina es el de \u201cperfeccionar\u201d a los delincuentes, aparecen noticias que conceden un haz de luz para quienes, como nosotros, aun creemos que ese sea un lugar para una futura reinserci\u00f3n. En esta oportunidad se trata de los internos de la &hellip;<\/p>\n","protected":false},"author":1,"featured_media":2383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","iawp_total_views":8,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integrados"],"_links":{"self":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts\/2381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/comments?post=2381"}],"version-history":[{"count":0,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/posts\/2381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/media\/2383"}],"wp:attachment":[{"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/media?parent=2381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/categories?post=2381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jotaposta.com.ar\/jposta\/wp-json\/wp\/v2\/tags?post=2381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}